{"id":24978,"date":"2024-09-30T19:04:55","date_gmt":"2024-09-30T19:04:55","guid":{"rendered":"https:\/\/tribeacai.com\/sorbet\/sorbet-a-lananas\/"},"modified":"2026-03-30T11:00:06","modified_gmt":"2026-03-30T11:00:06","slug":"fruit-du-dragon","status":"publish","type":"page","link":"https:\/\/tribeacai.com\/fr\/sorbet\/fruit-du-dragon\/","title":{"rendered":"Sorbet au Fruit du Dragon Tribe"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"24978\" class=\"elementor elementor-24978 elementor-19853\">\n\t\t\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-7820e05a elementor-section-content-top elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"7820e05a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3302290d\" data-id=\"3302290d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6bbdfa5b wd-width-100 elementor-widget elementor-widget-wd_images_gallery\" data-id=\"6bbdfa5b\" data-element_type=\"widget\" data-widget_type=\"wd_images_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-images-gallery photoswipe-images wd-carousel-container\" style=\"--wd-align-items:flex-start; --wd-justify-content:left;\">\n\t\t\t\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t\t<div class=\"wd-carousel wd-grid\" data-speed=\"2000\" data-wrap=\"yes\" data-autoplay=\"yes\" data-autoheight=\"yes\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:1;--wd-col-md:1;--wd-col-sm:1;--wd-gap-lg:6px;\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-1.webp\" data-width=\"876\" data-height=\"1000\" data-index=\"1\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"876\" height=\"1000\" src=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-1.webp\" class=\"attachment-full size-full\" alt=\"Sorbet de pitaia da Tribe A\u00e7a\u00ed, com cor vibrante e sabor delicado de pitaia\" srcset=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-1.webp 876w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-1-263x300.webp 263w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-1-701x800.webp 701w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-1-768x877.webp 768w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-1-600x685.webp 600w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-1-150x171.webp 150w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-1-300x342.webp 300w\" sizes=\"auto, (max-width: 876px) 100vw, 876px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-3.webp\" data-width=\"876\" data-height=\"1000\" data-index=\"2\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"876\" height=\"1000\" src=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-3.webp\" class=\"attachment-full size-full\" alt=\"Textura suave e cremosa do sorbet de pitaia Tribe, feito com fruta selecionada e ingredientes 100% naturais\" srcset=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-3.webp 876w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-3-263x300.webp 263w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-3-701x800.webp 701w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-3-768x877.webp 768w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-3-600x685.webp 600w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-3-150x171.webp 150w\" sizes=\"auto, (max-width: 876px) 100vw, 876px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<a  href=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/10\/Tribe-Acai-Sorbet-pitaia-caixa.webp\" data-width=\"876\" data-height=\"1000\" data-index=\"3\" data-elementor-open-lightbox=\"no\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"876\" height=\"1000\" src=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/10\/Tribe-Acai-Sorbet-pitaia-caixa.webp\" class=\"attachment-full size-full\" alt=\"Embalagem 900 ml do sorbet de pitaia Tribe servido pronto a consumir, sobremesa leve, tropical e visualmente vibrante\" srcset=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/10\/Tribe-Acai-Sorbet-pitaia-caixa.webp 876w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/10\/Tribe-Acai-Sorbet-pitaia-caixa-263x300.webp 263w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/10\/Tribe-Acai-Sorbet-pitaia-caixa-701x800.webp 701w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/10\/Tribe-Acai-Sorbet-pitaia-caixa-768x877.webp 768w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/10\/Tribe-Acai-Sorbet-pitaia-caixa-600x685.webp 600w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/10\/Tribe-Acai-Sorbet-pitaia-caixa-150x171.webp 150w\" sizes=\"auto, (max-width: 876px) 100vw, 876px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-nav-pagin-wrap text-center wd-style-shape wd-hide-md-sm wd-hide-sm\">\n\t\t\t<ul class=\"wd-nav-pagin\"><\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-2d0edeb2\" data-id=\"2d0edeb2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eeeec54 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"eeeec54\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-primary wd-title-style-default wd-title-size-medium text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h1 class=\"woodmart-title-container title wd-fontsize-xl\">Sorbet au Fruit du Dragon Tribe<\/h1> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title reset-last-child wd-fontsize-s\">\n\t\t\t\t\t<p><span class=\"notion-enable-hover\">Magnifique<\/span>!<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b8922f5 elementor-widget elementor-widget-wd_text_block\" data-id=\"6b8922f5\" data-element_type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>Le sorbet au fruit du dragon Tribe est <strong><span style=\"color: #da3a94;\">naturel et sain<\/span><\/strong>.<\/p><p>Notre recette naturelle et \u00e9quilibr\u00e9e met en valeur sa saveur originale, o\u00f9 il n'y a pas de place pour les \u00e9dulcorants, les ar\u00f4mes ou autres ingr\u00e9dients difficiles \u00e0 prononcer.<\/p><p>Il se distingue par sa couleur \u00e9clatante, sa texture unique et son go\u00fbt sublime, associ\u00e9s \u00e0 un faible indice calorique. Pr\u00eat \u00e0 \u00eatre consomm\u00e9 et d\u00e9gust\u00e9, le sorbet au fruit du dragon Tribe pr\u00e9sente une texture parfaite d\u00e8s sa sortie du cong\u00e9lateur, vous offrant une exp\u00e9rience sensorielle unique et inoubliable.<\/p><p><strong><span style=\"color: #650e5c;\">Il ne contient pas :<\/span><\/strong>\u00a0conservateurs, additifs de synth\u00e8se et est exempt d\u2019OGM.<\/p><h4><strong><span class=\"notion-enable-hover\" style=\"color: #339966;\" data-token-index=\"0\">Nous maintenons sain, ce qui est sain!<\/span><\/strong><\/h4>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49fb9bf elementor-widget elementor-widget-image-carousel\" data-id=\"49fb9bf\" data-element_type=\"widget\" data-settings=\"{&quot;navigation&quot;:&quot;none&quot;,&quot;autoplay&quot;:&quot;no&quot;,&quot;infinite&quot;:&quot;no&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:30,&quot;sizes&quot;:[]},&quot;slides_to_show&quot;:&quot;4&quot;,&quot;slides_to_show_mobile&quot;:&quot;4&quot;,&quot;speed&quot;:500,&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Carrousel d\u2019images\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"polite\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 sur 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Selo-produto-100-natural.svg\" alt=\"Selo Produto 100% Natural - Tribe A\u00e7a\u00ed\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 sur 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/03\/acai-logo-site-icons-copy-20.svg\" alt=\"Logotipo V-Label - Vegan - Tribe A\u00e7a\u00ed\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 sur 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2025\/01\/Tribe-Escolha-Sustentavel.png\" alt=\"Selo Escolha Sustent\u00e1vel Tribe A\u00e7a\u00ed \u2013 produtos veganos e saud\u00e1veis da Amaz\u00f3nia\" \/><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 sur 4\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/03\/selo-portugal-sou-eu.svg\" alt=\"Selo \u201cPortugal Sou Eu\u201d da Tribe A\u00e7a\u00ed, destacando a produ\u00e7\u00e3o nacional e compromisso com produtos portugueses de qualidade\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e48c20 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6e48c20\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-625a111 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-wd_text_block\" data-id=\"625a111\" data-element_type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<strong>Emballage disponible:<\/strong>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dc46e4c elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-wd_infobox_carousel\" data-id=\"dc46e4c\" data-element_type=\"widget\" data-widget_type=\"wd_infobox_carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-carousel-container info-box-carousel-wrapper\">\n\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t<div class=\"wd-carousel wd-grid info-box-carousel\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:3.5;--wd-col-md:3;--wd-col-sm:2;--wd-gap-lg:0px;\">\n\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-wrapper wd-carousel-item\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-left box-style-base color-scheme-  elementor-repeater-item-8c1696f wd-items-middle\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-svg-wrapper\" style=\"width:30px; height:30px;\"><img decoding=\"async\"  src=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/02\/acai-tamanho-embalagem.svg\" title=\"Tamanho Embalagem &#8211; Tribe Ac\u0327ai\u0301\" loading=\"lazy\" width=\"30\" height=\"30\"><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-default wd-fontsize-s\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\t900 ml\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"data-elementor-setting-key=\"content\"><\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-box-wrapper wd-carousel-item\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-left box-style-base color-scheme-  elementor-repeater-item-c4fc7b0 wd-items-middle\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-svg-wrapper\" style=\"width:30px; height:30px;\"><img decoding=\"async\"  src=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/02\/acai-tamanho-embalagem.svg\" title=\"Tamanho Embalagem &#8211; Tribe Ac\u0327ai\u0301\" loading=\"lazy\" width=\"30\" height=\"30\"><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t<h4\t\t\t\t\t\tclass=\"info-box-title title box-title-style-default wd-fontsize-s\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\t\t2,5L\t\t\t\t\t\t<\/h4>\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"data-elementor-setting-key=\"content\"><\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bdb0eef elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"bdb0eef\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e799106 elementor-widget__width-auto elementor-widget-mobile__width-inherit elementor-widget elementor-widget-wd_button\" data-id=\"e799106\" data-element_type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-default btn-shape-round btn-size-default btn-color-primary btn-icon-pos-right\"  href=\"https:\/\/tribeacai.com\/fr\/b2b\/\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\tJe veux vendre des sorbets Tribe\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-368f3f00 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"368f3f00\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d3fa37f\" data-id=\"d3fa37f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-097f699 elementor-widget elementor-widget-wd_image_or_svg\" data-id=\"097f699\" data-element_type=\"widget\" data-widget_type=\"wd_image_or_svg.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n\t\t<div class=\"wd-image text-center\">\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/10\/fotos-frutapit.webp\" class=\"attachment-full size-full\" alt=\"Pitaia vibrante e colorida, ingrediente natural dos sorbets da Tribe A\u00e7a\u00ed\" srcset=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/10\/fotos-frutapit.webp 1000w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/10\/fotos-frutapit-300x300.webp 300w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/10\/fotos-frutapit-800x800.webp 800w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/10\/fotos-frutapit-150x150.webp 150w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/10\/fotos-frutapit-768x768.webp 768w, https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/10\/fotos-frutapit-600x600.webp 600w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-41783892\" data-id=\"41783892\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10f75739 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"10f75739\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-default text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-l\">Connaissez-vous le fruit du dragon ?<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title reset-last-child wd-fontsize-xs\">\n\t\t\t\t\t<p>La pitaia, \u00e9galement appel\u00e9e fruit du dragon, est riche en <span style=\"color: #7bc142\"><strong>fibres<\/strong><\/span> et en min\u00e9raux, notamment en fer et en vitamine A, ainsi qu'en polyph\u00e9nols, qui lui conf\u00e8rent un important pouvoir <span style=\"color: #7bc142\"><strong>antioxydant<\/strong><\/span>.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"wd-negative-gap elementor-section elementor-top-section elementor-element elementor-element-a504c3d elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a504c3d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-15dbc97\" data-id=\"15dbc97\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c292e7 elementor-widget elementor-widget-image\" data-id=\"8c292e7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1142\" src=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2025\/01\/Sorbet-au-fruit-du-dragon-Tribe-Acai-Naturel-Sain-et-simple-scaled.webp\" class=\"attachment-full size-full wp-image-24982\" alt=\"\" srcset=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2025\/01\/Sorbet-au-fruit-du-dragon-Tribe-Acai-Naturel-Sain-et-simple-scaled.webp 2560w, https:\/\/tribeacai.com\/wp-content\/uploads\/2025\/01\/Sorbet-au-fruit-du-dragon-Tribe-Acai-Naturel-Sain-et-simple-400x178.webp 400w, https:\/\/tribeacai.com\/wp-content\/uploads\/2025\/01\/Sorbet-au-fruit-du-dragon-Tribe-Acai-Naturel-Sain-et-simple-1300x580.webp 1300w, https:\/\/tribeacai.com\/wp-content\/uploads\/2025\/01\/Sorbet-au-fruit-du-dragon-Tribe-Acai-Naturel-Sain-et-simple-768x342.webp 768w, https:\/\/tribeacai.com\/wp-content\/uploads\/2025\/01\/Sorbet-au-fruit-du-dragon-Tribe-Acai-Naturel-Sain-et-simple-1536x685.webp 1536w, https:\/\/tribeacai.com\/wp-content\/uploads\/2025\/01\/Sorbet-au-fruit-du-dragon-Tribe-Acai-Naturel-Sain-et-simple-2048x913.webp 2048w, https:\/\/tribeacai.com\/wp-content\/uploads\/2025\/01\/Sorbet-au-fruit-du-dragon-Tribe-Acai-Naturel-Sain-et-simple-600x268.webp 600w, https:\/\/tribeacai.com\/wp-content\/uploads\/2025\/01\/Sorbet-au-fruit-du-dragon-Tribe-Acai-Naturel-Sain-et-simple-1200x535.webp 1200w, https:\/\/tribeacai.com\/wp-content\/uploads\/2025\/01\/Sorbet-au-fruit-du-dragon-Tribe-Acai-Naturel-Sain-et-simple-150x67.webp 150w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-174732b e-con-full wd-section-stretch-content e-flex e-con e-parent\" data-id=\"174732b\" data-element_type=\"container\" id=\"info\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-5a63598 e-con-full e-flex e-con e-child\" data-id=\"5a63598\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65b3465 elementor-widget elementor-widget-wd_tabs\" data-id=\"65b3465\" data-element_type=\"widget\" data-widget_type=\"wd_tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-tabs tabs-design-default\">\n\t\t\t<div class=\"wd-tabs-header text-center\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"wd-nav-wrapper wd-nav-tabs-wrapper color-scheme-custom\">\n\t\t\t\t\t<ul class=\"wd-nav wd-nav-tabs wd-icon-pos-left wd-style-underline\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<a href=\"#\" class=\"wd-nav-link\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"nav-link-text wd-tabs-title\">\n\t\t\t\t\t\t\t\t\t\tTableau nutritionnel\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<li>\n\t\t\t\t\t\t\t\t<a href=\"#\" class=\"wd-nav-link\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"nav-link-text wd-tabs-title\">\n\t\t\t\t\t\t\t\t\t\tSuggestions de pr\u00e9paration\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/li>\n\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"wd-tabs-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-tab-content wd-entry-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<link rel=\"stylesheet\" id=\"elementor-post-19711-css\" href=\"https:\/\/tribeacai.com\/wp-content\/uploads\/elementor\/css\/post-19711.css?ver=1778663459\" type=\"text\/css\" media=\"all\">\n\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"19711\" class=\"elementor elementor-19711\">\n\t\t\t\t<div class=\"elementor-element elementor-element-baac6f2 e-con-full tabela-nutricional-html e-flex e-con e-parent\" data-id=\"baac6f2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-399fb69 eael-dt-th-align-center eael-table-align-center elementor-widget elementor-widget-eael-data-table\" data-id=\"399fb69\" data-element_type=\"widget\" data-widget_type=\"eael-data-table.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"eael-data-table-wrap\" data-table_id=\"399fb69\" id=\"eael-data-table-wrapper-399fb69\" data-custom_responsive=\"false\">\n\t\t\t<table class=\"tablesorter eael-data-table center\" id=\"eael-data-table-399fb69\">\n\t\t\t    <thead>\n\t\t\t        <tr class=\"table-header\">\n\t\t\t\t\t\t\t\t\t            <th class=\"\" id=\"\" colspan=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"data-table-header-text\"><\/span><\/th>\n\t\t\t        \t\t\t\t            <th class=\"\" id=\"\" colspan=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"data-table-header-text\">100mL<\/span><\/th>\n\t\t\t        \t\t\t\t        <\/tr>\n\t\t\t    <\/thead>\n\t\t\t  \t<tbody>\n\t\t\t\t\t\t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tEnergia | Energy | \u00c9nergie\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t360 kj \/ 86 kcal\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t        \t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tL\u00edpidos | Fat | Lipides\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t&lt;0,18 g\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t        \t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tDos quais Saturados | Of which Saturates | Dont Satur\u00e9s\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t&lt;0,09 g\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t        \t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tHidratos de Carbono | Carbohydrates | Glucides\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t20,7 g\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t        \t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tDos quais a\u00e7\u00facares | Of which sugars | Sucres\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t18,4 g\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t        \t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tFibra | Fiber | Fibre\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t1,1 g\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t        \t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tProte\u00ednas | Protein | Prot\u00e9ines\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t&lt;0,54 g\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t        \t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tSal | Salt | Sel\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t0,05 g\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t        \t\t\t\t\t\t<tr>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\tNUTRI-SCORE\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t   \t\t\t\t\t\t\t\t\t\t\t<td colspan=\"\" rowspan=\"\" class=\"\" id=\"\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"td-content-wrapper\"><div class=\"td-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" class=\"alignnone size-medium wp-image-18256\" src=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/nutri-B-score-tribe.svg\" alt=\"\" width=\"25%\" height=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div><\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/td>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/tr>\n\t\t\t        \t\t\t    <\/tbody>\n\t\t\t<\/table>\n\t\t<\/div>\n\t  \t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t<div class=\"wd-tab-content wd-entry-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<link rel=\"stylesheet\" id=\"elementor-post-24829-css\" href=\"https:\/\/tribeacai.com\/wp-content\/uploads\/elementor\/css\/post-24829.css?ver=1778657765\" type=\"text\/css\" media=\"all\">\n\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"24829\" class=\"elementor elementor-24829 elementor-16575 elementor-16575\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-c447e5f wd-section-stretch e-flex e-con-boxed e-con e-parent\" data-id=\"c447e5f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-db58a29 e-con-full e-flex e-con e-child\" data-id=\"db58a29\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b04c66a wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"b04c66a\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-primary wd-title-style-default wd-title-size-large text-center\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-xxl\">Suggestions de Pr\u00e9paration<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title reset-last-child wd-fontsize-s\">\n\t\t\t\t\tInspirez-vous de nos recettes et laissez libre cours \u00e0 votre cr\u00e9ativit\u00e9 !\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12f85f3 e-con-full wd-section-stretch e-flex e-con e-parent\" data-id=\"12f85f3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-49981c0 e-con-full e-flex e-con e-child\" data-id=\"49981c0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-237194f wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"237194f\" data-element_type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-medium text-center\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"title-subtitle subtitle-color-default subtitle-style-default wd-fontsize-xs\">\n\t\t\t\t\tSorbet au Fruit du Dragon Tribe\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-xl\">Questions Fr\u00e9quentes<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1ae760 faqsb2b elementor-widget elementor-widget-toggle\" data-id=\"a1ae760\" data-element_type=\"widget\" data-widget_type=\"toggle.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle\">\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1691\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1691\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Le sorbet au fruit du dragon Tribe est-il vegan \/ sans lactose \/ sans gluten \/ sans OGM?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1691\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1691\"><p>Oui ! Tous les sorbets Tribe sont\u00a0<strong>certifi\u00e9s vegan<\/strong>\u00a0par l&rsquo;organisme de certification V-Label, ce qui garantit qu&rsquo;ils ne contiennent ni produits animaux ni lactose. Ils sont \u00e9galement exempts de gluten, de colorants, de conservateurs, d&rsquo;additifs synth\u00e9tiques et d&rsquo;OGM. Ces caract\u00e9ristiques font de nos sorbets des produits id\u00e9aux pour les personnes souffrant d&rsquo;allergies, de restrictions alimentaires ou de pr\u00e9f\u00e9rences qui suivent des r\u00e9gimes vegan, v\u00e9g\u00e9tariens ou sans gluten.<\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1692\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1692\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quelle est le fruit du dragon utilis\u00e9e dans le sorbet au fruit du dragon Tribe?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1692\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1692\">Nous utilisons le fruit du dragon rose dans notre sorbet au fruit du dragon, ce qui lui donne sa couleur rose vif. Cette vari\u00e9t\u00e9 de fruit du dragon n&rsquo;est pas seulement attrayante sur le plan visuel, elle est \u00e9galement riche en nutriments et en antioxydants, et constitue une excellente source de fibres et de vitamine C. Notre sorbet est ainsi une option saine et savoureuse.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1693\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1693\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">Quel est le go\u00fbt du fruit du dragon rose?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1693\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1693\">Le fruit du dragon rose est connu pour sa saveur douce et l\u00e9g\u00e8rement sucr\u00e9e, avec des notes rappelant le kiwi et la poire. Sa texture croquante et sa chair juteuse et rafra\u00eechissante en font une ingr\u00e9dient id\u00e9al pour r\u00e9aliser un sorbet exceptionnellement rafra\u00eechissant et unique, qui offre une exp\u00e9rience d\u00e9licieuse et revitalisante \u00e0 chaque bouch\u00e9e.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-toggle-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1694\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1694\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon elementor-toggle-icon-right\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-closed\"><svg class=\"e-font-icon-svg e-fas-caret-right\" viewBox=\"0 0 192 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M0 384.662V127.338c0-17.818 21.543-26.741 34.142-14.142l128.662 128.662c7.81 7.81 7.81 20.474 0 28.284L34.142 398.804C21.543 411.404 0 402.48 0 384.662z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-toggle-icon-opened\"><svg class=\"elementor-toggle-icon-opened e-font-icon-svg e-fas-caret-up\" viewBox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288.662 352H31.338c-17.818 0-26.741-21.543-14.142-34.142l128.662-128.662c7.81-7.81 20.474-7.81 28.284 0l128.662 128.662c12.6 12.599 3.676 34.142-14.142 34.142z\"><\/path><\/svg><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-toggle-title\" tabindex=\"0\">D'o\u00f9 vient le fruit du dragon?<\/a>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div id=\"elementor-tab-content-1694\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1694\">Le fruit du dragon est originaire du Mexique, d&rsquo;Am\u00e9rique centrale et d&rsquo;Am\u00e9rique du Sud. Cependant, sa popularit\u00e9 s&rsquo;est rapidement r\u00e9pandue et elle est aujourd&rsquo;hui produite dans diverses parties du monde, en particulier dans plusieurs pays asiatiques.<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Le sorbet au fruit du dragon Tribe est-il vegan \\\/ sans lactose \\\/ sans gluten \\\/ sans OGM?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"<p>Oui ! Tous les sorbets Tribe sont\\u00a0<strong>certifi\\u00e9s vegan<\\\/strong>\\u00a0par l&rsquo;organisme de certification V-Label, ce qui garantit qu&rsquo;ils ne contiennent ni produits animaux ni lactose. Ils sont \\u00e9galement exempts de gluten, de colorants, de conservateurs, d&rsquo;additifs synth\\u00e9tiques et d&rsquo;OGM. Ces caract\\u00e9ristiques font de nos sorbets des produits id\\u00e9aux pour les personnes souffrant d&rsquo;allergies, de restrictions alimentaires ou de pr\\u00e9f\\u00e9rences qui suivent des r\\u00e9gimes vegan, v\\u00e9g\\u00e9tariens ou sans gluten.<\\\/p>\"}},{\"@type\":\"Question\",\"name\":\"Quelle est le fruit du dragon utilis\\u00e9e dans le sorbet au fruit du dragon Tribe?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Nous utilisons le fruit du dragon rose dans notre sorbet au fruit du dragon, ce qui lui donne sa couleur rose vif. Cette vari\\u00e9t\\u00e9 de fruit du dragon n&rsquo;est pas seulement attrayante sur le plan visuel, elle est \\u00e9galement riche en nutriments et en antioxydants, et constitue une excellente source de fibres et de vitamine C. Notre sorbet est ainsi une option saine et savoureuse.\"}},{\"@type\":\"Question\",\"name\":\"Quel est le go\\u00fbt du fruit du dragon rose?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Le fruit du dragon rose est connu pour sa saveur douce et l\\u00e9g\\u00e8rement sucr\\u00e9e, avec des notes rappelant le kiwi et la poire. Sa texture croquante et sa chair juteuse et rafra\\u00eechissante en font une ingr\\u00e9dient id\\u00e9al pour r\\u00e9aliser un sorbet exceptionnellement rafra\\u00eechissant et unique, qui offre une exp\\u00e9rience d\\u00e9licieuse et revitalisante \\u00e0 chaque bouch\\u00e9e.\"}},{\"@type\":\"Question\",\"name\":\"D'o\\u00f9 vient le fruit du dragon?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Le fruit du dragon est originaire du Mexique, d&rsquo;Am\\u00e9rique centrale et d&rsquo;Am\\u00e9rique du Sud. Cependant, sa popularit\\u00e9 s&rsquo;est rapidement r\\u00e9pandue et elle est aujourd&rsquo;hui produite dans diverses parties du monde, en particulier dans plusieurs pays asiatiques.\"}}]}<\/script>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sorbet au Fruit du Dragon Tribe Magnifique! Le sorbet au fruit du dragon Tribe est naturel et sain. Notre recette<\/p>\n","protected":false},"author":1,"featured_media":22259,"parent":24868,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-24978","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sorbet au Fruit du Dragon | Vibrant | Tribe A\u00e7a\u00ed<\/title>\n<meta name=\"description\" content=\"Go\u00fbtez \u00e0 l&#039;\u00e9blouissant Sorbet au Fruit du Dragon Tribe 100% naturel e sain. Une option pleine de couleurs avec une saveur inoubliable.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tribeacai.com\/fr\/sorbet\/fruit-du-dragon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sorbet au Fruit du Dragon | Vibrant | Tribe A\u00e7a\u00ed\" \/>\n<meta property=\"og:description\" content=\"Go\u00fbtez \u00e0 l&#039;\u00e9blouissant Sorbet au Fruit du Dragon Tribe 100% naturel e sain. Une option pleine de couleurs avec une saveur inoubliable.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tribeacai.com\/fr\/sorbet\/fruit-du-dragon\/\" \/>\n<meta property=\"og:site_name\" content=\"Tribe A\u00e7a\u00ed\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Tribeacaii\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-30T11:00:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"876\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/sorbet\\\/fruit-du-dragon\\\/\",\"url\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/sorbet\\\/fruit-du-dragon\\\/\",\"name\":\"Sorbet au Fruit du Dragon | Vibrant | Tribe A\u00e7a\u00ed\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/sorbet\\\/fruit-du-dragon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/sorbet\\\/fruit-du-dragon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tribeacai.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Tribe-Sorbet-Pitaia-1.webp\",\"datePublished\":\"2024-09-30T19:04:55+00:00\",\"dateModified\":\"2026-03-30T11:00:06+00:00\",\"description\":\"Go\u00fbtez \u00e0 l'\u00e9blouissant Sorbet au Fruit du Dragon Tribe 100% naturel e sain. Une option pleine de couleurs avec une saveur inoubliable.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/sorbet\\\/fruit-du-dragon\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tribeacai.com\\\/fr\\\/sorbet\\\/fruit-du-dragon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/sorbet\\\/fruit-du-dragon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tribeacai.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Tribe-Sorbet-Pitaia-1.webp\",\"contentUrl\":\"https:\\\/\\\/tribeacai.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Tribe-Sorbet-Pitaia-1.webp\",\"width\":876,\"height\":1000,\"caption\":\"Sorbet de pitaia da Tribe A\u00e7a\u00ed, com cor vibrante e sabor delicado de pitaia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/sorbet\\\/fruit-du-dragon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sorbets\",\"item\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/sorbet\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Sorbet au Fruit du Dragon Tribe\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/\",\"name\":\"Tribe A\u00e7a\u00ed\",\"description\":\"The Native Food\",\"publisher\":{\"@id\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/#organization\"},\"alternateName\":\"Tribe\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/#organization\",\"name\":\"Tribe A\u00e7a\u00ed\",\"url\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tribeacai.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/acai-logo-site-1.png\",\"contentUrl\":\"https:\\\/\\\/tribeacai.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/acai-logo-site-1.png\",\"width\":600,\"height\":600,\"caption\":\"Tribe A\u00e7a\u00ed\"},\"image\":{\"@id\":\"https:\\\/\\\/tribeacai.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Tribeacaii\\\/\",\"https:\\\/\\\/www.instagram.com\\\/tribe_acai\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/tribe-acai\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sorbet au Fruit du Dragon | Vibrant | Tribe A\u00e7a\u00ed","description":"Go\u00fbtez \u00e0 l'\u00e9blouissant Sorbet au Fruit du Dragon Tribe 100% naturel e sain. Une option pleine de couleurs avec une saveur inoubliable.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tribeacai.com\/fr\/sorbet\/fruit-du-dragon\/","og_locale":"fr_FR","og_type":"article","og_title":"Sorbet au Fruit du Dragon | Vibrant | Tribe A\u00e7a\u00ed","og_description":"Go\u00fbtez \u00e0 l'\u00e9blouissant Sorbet au Fruit du Dragon Tribe 100% naturel e sain. Une option pleine de couleurs avec une saveur inoubliable.","og_url":"https:\/\/tribeacai.com\/fr\/sorbet\/fruit-du-dragon\/","og_site_name":"Tribe A\u00e7a\u00ed","article_publisher":"https:\/\/www.facebook.com\/Tribeacaii\/","article_modified_time":"2026-03-30T11:00:06+00:00","og_image":[{"width":876,"height":1000,"url":"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tribeacai.com\/fr\/sorbet\/fruit-du-dragon\/","url":"https:\/\/tribeacai.com\/fr\/sorbet\/fruit-du-dragon\/","name":"Sorbet au Fruit du Dragon | Vibrant | Tribe A\u00e7a\u00ed","isPartOf":{"@id":"https:\/\/tribeacai.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tribeacai.com\/fr\/sorbet\/fruit-du-dragon\/#primaryimage"},"image":{"@id":"https:\/\/tribeacai.com\/fr\/sorbet\/fruit-du-dragon\/#primaryimage"},"thumbnailUrl":"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-1.webp","datePublished":"2024-09-30T19:04:55+00:00","dateModified":"2026-03-30T11:00:06+00:00","description":"Go\u00fbtez \u00e0 l'\u00e9blouissant Sorbet au Fruit du Dragon Tribe 100% naturel e sain. Une option pleine de couleurs avec une saveur inoubliable.","breadcrumb":{"@id":"https:\/\/tribeacai.com\/fr\/sorbet\/fruit-du-dragon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tribeacai.com\/fr\/sorbet\/fruit-du-dragon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tribeacai.com\/fr\/sorbet\/fruit-du-dragon\/#primaryimage","url":"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-1.webp","contentUrl":"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/09\/Tribe-Sorbet-Pitaia-1.webp","width":876,"height":1000,"caption":"Sorbet de pitaia da Tribe A\u00e7a\u00ed, com cor vibrante e sabor delicado de pitaia"},{"@type":"BreadcrumbList","@id":"https:\/\/tribeacai.com\/fr\/sorbet\/fruit-du-dragon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/tribeacai.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Sorbets","item":"https:\/\/tribeacai.com\/fr\/sorbet\/"},{"@type":"ListItem","position":3,"name":"Sorbet au Fruit du Dragon Tribe"}]},{"@type":"WebSite","@id":"https:\/\/tribeacai.com\/fr\/#website","url":"https:\/\/tribeacai.com\/fr\/","name":"Tribe A\u00e7a\u00ed","description":"The Native Food","publisher":{"@id":"https:\/\/tribeacai.com\/fr\/#organization"},"alternateName":"Tribe","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tribeacai.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/tribeacai.com\/fr\/#organization","name":"Tribe A\u00e7a\u00ed","url":"https:\/\/tribeacai.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/tribeacai.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/02\/acai-logo-site-1.png","contentUrl":"https:\/\/tribeacai.com\/wp-content\/uploads\/2024\/02\/acai-logo-site-1.png","width":600,"height":600,"caption":"Tribe A\u00e7a\u00ed"},"image":{"@id":"https:\/\/tribeacai.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Tribeacaii\/","https:\/\/www.instagram.com\/tribe_acai\/","https:\/\/www.linkedin.com\/company\/tribe-acai\/"]}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/tribeacai.com\/fr\/wp-json\/wp\/v2\/pages\/24978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tribeacai.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tribeacai.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tribeacai.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/tribeacai.com\/fr\/wp-json\/wp\/v2\/comments?post=24978"}],"version-history":[{"count":6,"href":"https:\/\/tribeacai.com\/fr\/wp-json\/wp\/v2\/pages\/24978\/revisions"}],"predecessor-version":[{"id":26205,"href":"https:\/\/tribeacai.com\/fr\/wp-json\/wp\/v2\/pages\/24978\/revisions\/26205"}],"up":[{"embeddable":true,"href":"https:\/\/tribeacai.com\/fr\/wp-json\/wp\/v2\/pages\/24868"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tribeacai.com\/fr\/wp-json\/wp\/v2\/media\/22259"}],"wp:attachment":[{"href":"https:\/\/tribeacai.com\/fr\/wp-json\/wp\/v2\/media?parent=24978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}